{"id":850,"date":"2022-06-27T10:44:59","date_gmt":"2022-06-27T10:44:59","guid":{"rendered":"https:\/\/blessingdigit.site\/wp\/?p=850"},"modified":"2022-11-09T10:40:46","modified_gmt":"2022-11-09T10:40:46","slug":"offres-de-partenariat-et-de-sponsoring-de-la-2eme-edition-du-fiprod-2","status":"publish","type":"post","link":"https:\/\/fiprod.ersuma.org\/fr_fr\/2022\/06\/27\/offres-de-partenariat-et-de-sponsoring-de-la-2eme-edition-du-fiprod-2\/","title":{"rendered":"D\u00c9V\u00c9LOPPEMENT \u00c9CONOMIQUE ET D\u00c9FIS DU FINANCEMENT DES ENTREPRISES EN AFRIQUE"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"850\" class=\"elementor elementor-850\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34fc1cf9 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"34fc1cf9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-699cd2bc\" data-id=\"699cd2bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39038266 elementor-align-left elementor-widget__width-auto elementor-widget elementor-widget-elementskit-button\" data-id=\"39038266\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"ekit-btn-wraper\">\n\t\t\t\t\t\t\t<a href=\"http:\/\/fiprod.ersuma.org\/fr_fr\/\" class=\"elementskit-btn  whitespace--normal\" id=\"\">\n\t\t\t\t\taccueil\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6047b57e elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"6047b57e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">\/<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52ce8d89 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"52ce8d89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Communiqu\u00e9 3<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aad331a elementor-widget elementor-widget-heading\" data-id=\"aad331a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> D\u00c9V\u00c9LOPPEMENT \u00c9CONOMIQUE ET D\u00c9FIS DU FINANCEMENT DES ENTREPRISES EN AFRIQUE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-338f3e7 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"338f3e7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a1c6701\" data-id=\"a1c6701\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e7a4fa5 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"e7a4fa5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-pulse\" href=\"https:\/\/fiprod.ersuma.org\/wp-content\/uploads\/2022\/10\/FR_Communique-FIPROD.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">T\u00e9l\u00e9charger<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c397a4b elementor-widget elementor-widget-heading\" data-id=\"c397a4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">D\u00c9V\u00c9LOPPEMENT \u00c9CONOMIQUE ET D\u00c9FIS DU FINANCEMENT DES ENTREPRISES EN AFRIQUE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2f272b7 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"2f272b7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-db45f4a\" data-id=\"db45f4a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36288c1 elementor-widget elementor-widget-image\" data-id=\"36288c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"513\" src=\"https:\/\/fiprod.ersuma.org\/wp-content\/uploads\/2022\/06\/DSC02887-1-1024x657.jpg\" class=\"attachment-large size-large wp-image-845\" alt=\"\" srcset=\"https:\/\/fiprod.ersuma.org\/wp-content\/uploads\/2022\/06\/DSC02887-1-1024x657.jpg 1024w, https:\/\/fiprod.ersuma.org\/wp-content\/uploads\/2022\/06\/DSC02887-1-300x192.jpg 300w, https:\/\/fiprod.ersuma.org\/wp-content\/uploads\/2022\/06\/DSC02887-1-768x493.jpg 768w, https:\/\/fiprod.ersuma.org\/wp-content\/uploads\/2022\/06\/DSC02887-1-1536x985.jpg 1536w, https:\/\/fiprod.ersuma.org\/wp-content\/uploads\/2022\/06\/DSC02887-1-2048x1314.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c7092a6\" data-id=\"c7092a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-88e8a5a elementor-widget elementor-widget-text-editor\" data-id=\"88e8a5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mesdames et messieurs,<br \/>La 2\u00e8me \u00e9dition du Forum international des professionnels du Droit et du Chiffre (FIPROD) est pr\u00e9vue pour tr\u00e8s bient\u00f4t, du 16 au 19 novembre 2022, au <strong>Park Inn Hotel by Radisson \u00e0 Kigali<\/strong> (Rwanda), sur le th\u00e8me : \u00ab D\u00e9veloppement \u00e9conomique et d\u00e9fis du financement des entreprises en Afrique \u00bb.<\/p><p style=\"background-image: initial; background-position: initial; background-size: initial; background-repeat: initial; background-attachment: initial; background-origin: initial; background-clip: initial;\">\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-278900d elementor-widget elementor-widget-text-editor\" data-id=\"278900d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pour rappel, le FIPROD est une manifestation professionnelle biannuelle de haut niveau qui se veut le trait d\u2019union entre les professionnels du Droit et du Chiffre, d\u2019horizons et de domaines divers, dont la collaboration interprofessionnelle est primordiale pour le d\u00e9veloppement de leur profession et la satisfaction des besoins l\u00e9gitimes qui justifient leur existence.<\/p><p>\u00a0<\/p><p>Ne ratez donc surtout pas ce grand rendez-vous international de d\u00e9couverte, de renforcement des capacit\u00e9s, de partage d\u2019exp\u00e9rience et de coop\u00e9ration professionnelle et interprofessionnelle.<\/p><p>\u00a0<\/p><p>Cette 2<sup>\u00e8me<\/sup>\u00a0\u00e9dition intervient dans un contexte marqu\u00e9 par une forte crise de viabilit\u00e9 et de fiabilit\u00e9 des entreprises africaines, qui ralentit consid\u00e9rablement l\u2019\u00e9mergence \u00e9conomique de l\u2019Afrique.\u00a0Elle vise principalement \u00e0 rechercher des solutions ad\u00e9quates \u00e0 la probl\u00e9matique du financement des entreprises pouvant contribuer efficacement \u00e0 l\u2019am\u00e9lioration du climat des investissements en Afrique.\u00a0<\/p><p>\u00a0<\/p><p>Participeront aux travaux les professionnels du Droit et du Chiffre, les institutions et organismes publics\/priv\u00e9s qui \u0153uvrent pour le financement des entreprises et le d\u00e9veloppement \u00e9conomique de l\u2019Afrique, les chefs d\u2019entreprises, investisseurs et jeunes entrepreneurs.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1e67a31 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"1e67a31\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f4a1d17\" data-id=\"f4a1d17\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7b9d64 elementor-widget elementor-widget-text-editor\" data-id=\"a7b9d64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table style=\"font-weight: 400;\" width=\"690\"><tbody><tr><td colspan=\"6\" width=\"690\"><p><strong><em>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0FRAIS DE PARTICIPATION <\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"151\"><p><strong><em>\u00a0<\/em><\/strong><\/p><\/td><td width=\"236\"><p><strong><em>P\u00e9riode <\/em><\/strong><\/p><\/td><td width=\"76\"><p><strong><em>En FCFA<\/em><\/strong><\/p><\/td><td width=\"76\"><p><strong><em>En FRW<\/em><\/strong><\/p><\/td><td width=\"76\"><p><strong><em>En \u20ac EUR<\/em><\/strong><\/p><\/td><td width=\"76\"><p><strong><em>En $ USD<\/em><\/strong><\/p><\/td><\/tr><tr><td width=\"151\"><p><strong><em>Tarif initial maintenu pour toute inscription<\/em><\/strong><\/p><\/td><td width=\"236\"><p><em>\u00a0<\/em><\/p><p><em>Au plus tard le 14 novembre 2022<\/em><\/p><p><em>\u00a0<\/em><\/p><\/td><td width=\"76\"><p>\u00a0<\/p><p>400.000<\/p><\/td><td width=\"76\"><p>\u00a0<\/p><p>670.000<\/p><\/td><td width=\"76\"><p>\u00a0<\/p><p>610<\/p><\/td><td width=\"76\"><p>\u00a0<\/p><p>700<\/p><\/td><\/tr><tr><td colspan=\"6\" width=\"690\"><p>&#8211; \u00a0<em>Les doctorants et \u00e9tudiants b\u00e9n\u00e9ficient d\u2019un tarif sp\u00e9cial de <strong>240.000 FCFA<\/strong> sur demande adress\u00e9e au Directeur G\u00e9n\u00e9ral de l\u2019ERSUMA comportant en pi\u00e8ce jointe une attestation d\u2019inscription valide couvrant la p\u00e9riode 2020 \u00e0 2022\u00a0; <\/em><\/p><p>&#8211;\u00a0<em>Les jeunes professionnels (avocats, notaires, huissiers de justice, experts-comptables et comptables agr\u00e9\u00e9s, etc) \u00e2g\u00e9s d\u2019au plus 35 ans au 31 d\u00e9cembre 2022 b\u00e9n\u00e9ficient d\u2019une r\u00e9duction de 10% sur demande. <\/em><\/p><p>&#8211;\u00a0<em>Une r\u00e9duction de 10% est accord\u00e9e pour toute inscription d\u2019un groupe d\u2019au-moins trois (03) personnes. <\/em><\/p><p>&#8211; \u00a0<em>Une r\u00e9duction de 20% est accord\u00e9e pour toute inscription d\u2019un groupe d\u2019au-moins dix (10) personnes.<\/em><\/p><\/td><\/tr><tr><td colspan=\"6\" width=\"690\"><p><strong><em>Les travaux se d\u00e9rouleront du 16 au 18 novembre au Park Inn Hotel by Radisson Kigali. <\/em><\/strong><\/p><p><strong><em>La soir\u00e9e de gala se tiendra au Kigali Convention Centre le vendredi 18 novembre apr\u00e8s les travaux.\u00a0 <\/em><\/strong><\/p><p><strong><em>La journ\u00e9e du 19 novembre est consacr\u00e9e \u00e0 la visite touristique. <\/em><\/strong><\/p><p><strong><em>NB\u00a0: Les frais de participation couvrent les supports et mat\u00e9riel p\u00e9dagogiques, les pauses caf\u00e9 et d\u00e9jeuner pendant les travaux, le diner de gala, la visite touristique et les activit\u00e9s sportives. <\/em><\/strong><\/p><\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>accueil \/ Communiqu\u00e9 3 D\u00c9V\u00c9LOPPEMENT \u00c9CONOMIQUE ET D\u00c9FIS DU FINANCEMENT DES ENTREPRISES EN AFRIQUE T\u00e9l\u00e9charger D\u00c9V\u00c9LOPPEMENT \u00c9CONOMIQUE ET D\u00c9FIS DU FINANCEMENT DES ENTREPRISES EN AFRIQUE Mesdames et messieurs,La 2\u00e8me \u00e9dition du Forum international des professionnels du Droit et du Chiffre (FIPROD) est pr\u00e9vue pour tr\u00e8s bient\u00f4t, du 16 au 19 novembre 2022, au Park Inn Hotel by Radisson \u00e0 Kigali (Rwanda), sur le th\u00e8me : \u00ab D\u00e9veloppement \u00e9conomique et d\u00e9fis du financement des entreprises en Afrique \u00bb. \u00a0 Pour rappel, le FIPROD est une manifestation professionnelle biannuelle de haut niveau qui se veut le trait d\u2019union entre les professionnels du Droit et du Chiffre, d\u2019horizons et de domaines divers, dont la collaboration interprofessionnelle est primordiale pour le d\u00e9veloppement de leur profession et la satisfaction des besoins l\u00e9gitimes qui justifient leur existence. \u00a0 Ne ratez donc surtout pas ce grand rendez-vous international de d\u00e9couverte, de renforcement des capacit\u00e9s, de partage d\u2019exp\u00e9rience et de coop\u00e9ration professionnelle et interprofessionnelle. \u00a0 Cette 2\u00e8me\u00a0\u00e9dition intervient dans un contexte marqu\u00e9 par une forte crise de viabilit\u00e9 et de fiabilit\u00e9 des entreprises africaines, qui ralentit consid\u00e9rablement l\u2019\u00e9mergence \u00e9conomique de l\u2019Afrique.\u00a0Elle vise principalement \u00e0 rechercher des solutions ad\u00e9quates \u00e0 la probl\u00e9matique du financement des entreprises pouvant contribuer efficacement \u00e0 l\u2019am\u00e9lioration du climat des investissements en Afrique.\u00a0 \u00a0 Participeront aux travaux les professionnels du Droit et du Chiffre, les institutions et organismes publics\/priv\u00e9s qui \u0153uvrent pour le financement des entreprises et le d\u00e9veloppement \u00e9conomique de l\u2019Afrique, les chefs d\u2019entreprises, investisseurs et jeunes entrepreneurs. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0FRAIS DE PARTICIPATION \u00a0 P\u00e9riode En FCFA En FRW En \u20ac EUR En $ USD Tarif initial maintenu pour toute inscription \u00a0 Au plus tard le 14 novembre 2022 \u00a0 \u00a0 400.000 \u00a0 670.000 \u00a0 610 \u00a0 700 &#8211; \u00a0Les doctorants et \u00e9tudiants b\u00e9n\u00e9ficient d\u2019un tarif sp\u00e9cial de 240.000 FCFA sur demande adress\u00e9e au Directeur G\u00e9n\u00e9ral de l\u2019ERSUMA comportant en pi\u00e8ce jointe une attestation d\u2019inscription valide couvrant la p\u00e9riode 2020 \u00e0 2022\u00a0; &#8211;\u00a0Les jeunes professionnels (avocats, notaires, huissiers de justice, experts-comptables et comptables agr\u00e9\u00e9s, etc) \u00e2g\u00e9s d\u2019au plus 35 ans au 31 d\u00e9cembre 2022 b\u00e9n\u00e9ficient d\u2019une r\u00e9duction de 10% sur demande. &#8211;\u00a0Une r\u00e9duction de 10% est accord\u00e9e pour toute inscription d\u2019un groupe d\u2019au-moins trois (03) personnes. &#8211; \u00a0Une r\u00e9duction de 20% est accord\u00e9e pour toute inscription d\u2019un groupe d\u2019au-moins dix (10) personnes. Les travaux se d\u00e9rouleront du 16 au 18 novembre au Park Inn Hotel by Radisson Kigali. La soir\u00e9e de gala se tiendra au Kigali Convention Centre le vendredi 18 novembre apr\u00e8s les travaux.\u00a0 La journ\u00e9e du 19 novembre est consacr\u00e9e \u00e0 la visite touristique. NB\u00a0: Les frais de participation couvrent les supports et mat\u00e9riel p\u00e9dagogiques, les pauses caf\u00e9 et d\u00e9jeuner pendant les travaux, le diner de gala, la visite touristique et les activit\u00e9s sportives.<\/p>\n","protected":false},"author":1,"featured_media":845,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,8],"tags":[],"class_list":["post-850","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ateliers","category-table-ronde"],"_links":{"self":[{"href":"https:\/\/fiprod.ersuma.org\/fr_fr\/wp-json\/wp\/v2\/posts\/850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fiprod.ersuma.org\/fr_fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fiprod.ersuma.org\/fr_fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fiprod.ersuma.org\/fr_fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fiprod.ersuma.org\/fr_fr\/wp-json\/wp\/v2\/comments?post=850"}],"version-history":[{"count":29,"href":"https:\/\/fiprod.ersuma.org\/fr_fr\/wp-json\/wp\/v2\/posts\/850\/revisions"}],"predecessor-version":[{"id":1140,"href":"https:\/\/fiprod.ersuma.org\/fr_fr\/wp-json\/wp\/v2\/posts\/850\/revisions\/1140"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fiprod.ersuma.org\/fr_fr\/wp-json\/wp\/v2\/media\/845"}],"wp:attachment":[{"href":"https:\/\/fiprod.ersuma.org\/fr_fr\/wp-json\/wp\/v2\/media?parent=850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fiprod.ersuma.org\/fr_fr\/wp-json\/wp\/v2\/categories?post=850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fiprod.ersuma.org\/fr_fr\/wp-json\/wp\/v2\/tags?post=850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}